{"id":4516,"date":"2021-02-24T10:49:18","date_gmt":"2021-02-24T09:49:18","guid":{"rendered":"https:\/\/verasturies.com\/?p=4516"},"modified":"2021-02-24T10:49:20","modified_gmt":"2021-02-24T09:49:20","slug":"ana-vanessa-gutierrez-escritora-de-una-obra-que-se-considera-unica-en-el-panorama-literario-asturiano","status":"publish","type":"post","link":"https:\/\/verasturies.com\/ast_ast\/ana-vanessa-gutierrez-escritora-de-una-obra-que-se-considera-unica-en-el-panorama-literario-asturiano\/","title":{"rendered":"Ana Vanessa Gutierrez: escritora de &#8220;una obra que se considera \u00fanica en el panorama literario asturiano&#8221;"},"content":{"rendered":"<p>La presentadora del magac\u00edn cultural Pieces de la nuesa cadena televisiva local naci\u00f3 en Mieres en 1980, a pesar de que lleva viviendo en L'Entrego dende los sos seis a\u00f1os. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/verasturies.com\/wp-content\/uploads\/2021\/02\/40303507-624x916-1.jpeg\" alt=\"\" class=\"wp-image-4519\" width=\"350\" height=\"514\" srcset=\"https:\/\/verasturies.com\/wp-content\/uploads\/2021\/02\/40303507-624x916-1.jpeg 624w, https:\/\/verasturies.com\/wp-content\/uploads\/2021\/02\/40303507-624x916-1-204x300.jpeg 204w, https:\/\/verasturies.com\/wp-content\/uploads\/2021\/02\/40303507-624x916-1-8x12.jpeg 8w, https:\/\/verasturies.com\/wp-content\/uploads\/2021\/02\/40303507-624x916-1-585x859.jpeg 585w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/figure><\/div>\n\n\n\n<p>Diose a conocer na poes\u00eda en 2003 col poemariu <em>&#8220;Onde seca l&#8217;agua&#8221;<\/em> qu'arrexuntaba los sos entamos como poeta n'asturianu. Al a\u00f1u siguiente foi galardonada col Premiu Teodoro Cuesta por <em>&#8220;La danza de la yedra&#8221;<\/em> pasando a facese conocida como una referente na poes\u00eda asturiana.  A parte del asturianu, tami\u00e9n tuvo presencia na lliteratura catalana onde ten\u00eda presencia en <strong>&#8220;Pass\u00e0 el temps desfant la mem\u00f3ria&#8221;<\/strong>.<\/p>\n\n\n\n<p>Ana quixo dir m\u00e1s all\u00e1 y sac\u00f3 a la lluz en 2006 la so primer obra narrativa <em>&#8220;Les palabres que te mando&#8221; <\/em>que sigui\u00f3 l'ensayu documental sobre la vida de muyeres asturianes mientres la Guerra Civil, <em>&#8220;El Pa\u00eds del silenciu&#8221;<\/em>. A lo \u00faltimo, cierra la so colecci\u00f3n de narrativa con <em>&#8220;La cama&#8221;,<\/em> el que ye ensin dala dulda el llibru m\u00e1s intensu de l'asturiana y que se considera una obra \u00fanica nel panorama lliterariu asturianu. <\/p>\n\n\n\n<p>Angua\u00f1o, apurre semanalmente la so conocencia cultural nel programa, pero tami\u00e9n dirixe y presenta el programa radiof\u00f3nicu de <em>&#8220;Entrel\u00edneas&#8221;<\/em> dedic\u00e1u a la lliteratura. Am\u00e1s, collabora dacuando n'El Comerciu y Les Noticies. <\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La presentadora del magazine cultural Pieces de la TPA naci\u00f3 en Mieres en 1980, a pesar de que lleva viviendo en El Entrego desde sus seis a\u00f1os. Se dio a conocer en la poes\u00eda en 2003 con el poemario &#8220;Onde seca l&#8217;agua&#8221; que recopilaba sus&#8230;<\/p>","protected":false},"author":1,"featured_media":4518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[328],"tags":[],"class_list":["post-4516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personalidades"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/posts\/4516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/comments?post=4516"}],"version-history":[{"count":0,"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/posts\/4516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/media\/4518"}],"wp:attachment":[{"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/media?parent=4516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/categories?post=4516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verasturies.com\/ast_ast\/wp-json\/wp\/v2\/tags?post=4516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}